{"id":144,"count":1,"description":"","link":"https:\/\/wwwcp.umes.edu\/scm\/tag\/philadelphia\/","name":"Philadelphia","slug":"philadelphia","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/wwwcp.umes.edu\/scm\/wp-json\/wp\/v2\/tags\/144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wwwcp.umes.edu\/scm\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/wwwcp.umes.edu\/scm\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/wwwcp.umes.edu\/scm\/wp-json\/wp\/v2\/posts?tags=144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}