{"id":1564,"date":"2021-05-27T21:54:08","date_gmt":"2021-05-27T21:54:08","guid":{"rendered":"https:\/\/wwwcp.umes.edu\/kinesiology\/?page_id=1564"},"modified":"2023-10-23T14:45:21","modified_gmt":"2023-10-23T18:45:21","slug":"annual-hawk-walk","status":"publish","type":"page","link":"https:\/\/wwwcp.umes.edu\/kinesiology\/annual-hawk-walk\/","title":{"rendered":"Annual Hawk Walk"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Annual Hawk Walk<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Every year, the Department of Kinesiology hosts a 2.5-mile walk around the Town of Princess Anne to raise awareness about the benefits of health and fitness in the community. Health screenings, games, and food are provided to the participants. The event is organized by the Department of Kinesiology faculty, staff, and students.<\/p>\n\n\n\n<div class=\"alignnormal\"><div id=\"metaslider-id-1540\" style=\"width: 100%;\" class=\"ml-slider-3-110-0 ml-slider-pro-2-58-0 metaslider metaslider-flex metaslider-1540 ml-slider has-dots-nav ms-theme-default\" role=\"region\" aria-label=\"Healthy Hawk Walk\" data-height=\"300\" data-width=\"700\">\n    <div id=\"metaslider_container_1540\">\n        <div id=\"metaslider_1540\">\n            <ul class='slides'>\n                <li style=\"display: block; width: 100%;\" class=\"slide-1555 ms-image \" aria-roledescription=\"slide\" data-date=\"2021-05-27 21:51:08\" data-filename=\"4-scaled-700x300.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/wwwcp.umes.edu\/kinesiology\/wp-content\/uploads\/sites\/22\/2023\/10\/4-scaled-700x300.jpg\" height=\"300\" width=\"700\" alt=\"\" class=\"slider-1540 slide-1555 msDefaultImage\" title=\"4\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-1558 ms-image \" aria-roledescription=\"slide\" data-date=\"2021-05-27 21:51:08\" data-filename=\"2-scaled-700x300.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/wwwcp.umes.edu\/kinesiology\/wp-content\/uploads\/sites\/22\/2023\/10\/2-scaled-700x300.jpg\" height=\"300\" width=\"700\" alt=\"\" class=\"slider-1540 slide-1558 msDefaultImage\" title=\"2\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-1559 ms-image \" aria-roledescription=\"slide\" data-date=\"2021-05-27 21:51:08\" data-filename=\"5-scaled-700x300.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/wwwcp.umes.edu\/kinesiology\/wp-content\/uploads\/sites\/22\/2023\/10\/5-scaled-700x300.jpg\" height=\"300\" width=\"700\" alt=\"\" class=\"slider-1540 slide-1559 msDefaultImage\" title=\"5\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-1560 ms-image \" aria-roledescription=\"slide\" data-date=\"2021-05-27 21:51:08\" data-filename=\"3-scaled-700x300.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/wwwcp.umes.edu\/kinesiology\/wp-content\/uploads\/sites\/22\/2023\/10\/3-scaled-700x300.jpg\" height=\"300\" width=\"700\" alt=\"\" class=\"slider-1540 slide-1560 msDefaultImage\" title=\"3\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-1957 ms-image \" aria-roledescription=\"slide\" data-date=\"2023-10-20 15:36:49\" data-filename=\"7-scaled-700x300.jpg\" data-slide-type=\"image\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/wwwcp.umes.edu\/kinesiology\/wp-content\/uploads\/sites\/22\/2023\/10\/7-scaled-700x300.jpg\" height=\"300\" width=\"700\" alt=\"\" class=\"slider-1540 slide-1957 msDefaultImage\" title=\"7\" \/><\/li>\n            <\/ul>\n        <\/div>\n        \n    <\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Annual Hawk Walk Every year, the Department of Kinesiology hosts a 2.5-mile walk around the Town of Princess Anne to raise awareness about the benefits of health and fitness in the community. Health screenings, games, and food are provided to the participants. The event is organized by the Department of Kinesiology faculty, staff, and students&#8230;.<span class=\"cpschool-read-more-link-holder\"><a class=\"btn btn-basic cpschool-read-more-link\" href=\"https:\/\/wwwcp.umes.edu\/kinesiology\/annual-hawk-walk\/\">Read more <span class=\"sr-only\">Annual Hawk Walk<\/span><\/a><\/span><\/p>\n","protected":false},"author":2,"featured_media":2060,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"folder":[],"class_list":["post-1564","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/wwwcp.umes.edu\/kinesiology\/wp-json\/wp\/v2\/pages\/1564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wwwcp.umes.edu\/kinesiology\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wwwcp.umes.edu\/kinesiology\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wwwcp.umes.edu\/kinesiology\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/wwwcp.umes.edu\/kinesiology\/wp-json\/wp\/v2\/comments?post=1564"}],"version-history":[{"count":0,"href":"https:\/\/wwwcp.umes.edu\/kinesiology\/wp-json\/wp\/v2\/pages\/1564\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wwwcp.umes.edu\/kinesiology\/wp-json\/wp\/v2\/media\/2060"}],"wp:attachment":[{"href":"https:\/\/wwwcp.umes.edu\/kinesiology\/wp-json\/wp\/v2\/media?parent=1564"}],"wp:term":[{"taxonomy":"folder","embeddable":true,"href":"https:\/\/wwwcp.umes.edu\/kinesiology\/wp-json\/wp\/v2\/folder?post=1564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}