{"id":2148,"date":"2025-06-12T14:46:42","date_gmt":"2025-06-12T18:46:42","guid":{"rendered":"https:\/\/wwwcp.umes.edu\/commencement\/?page_id=2148"},"modified":"2025-06-16T09:49:19","modified_gmt":"2025-06-16T13:49:19","slug":"2025-commencement-gallery","status":"publish","type":"page","link":"https:\/\/wwwcp.umes.edu\/commencement\/archives\/spring-2025-commencement\/2025-commencement-gallery\/","title":{"rendered":"Spring 2025 Commencement Gallery"},"content":{"rendered":"\n<div class=\"wp-block-cover has-parallax\"><div class=\"wp-block-cover__image-background wp-image-2137 size-large has-parallax\" style=\"background-position:50% 50%;background-image:url(https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/Image-88-1024x683.jpeg)\"><\/div><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim\" style=\"background-color:#4a2f2d\"><\/span><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-center has-white-color has-text-color has-link-color has-larger-font-size wp-elements-7327b2410296c0f6aa5d494a580d5050\">Spring 2025 Commencement Gallery<\/h2>\n<\/div><\/div>\n\n\n\n<div aria-label=\"Carousel Gallery\" class=\"wp-block-coblocks-gallery-carousel alignfull\"><div class=\"coblocks-gallery-carousel-swiper-container is-cropped coblocks-gallery has-border-radius-14 has-caption-style-dark has-horizontal-gutter has-lightbox has-no-thumbnails\"><div class=\"has-carousel has-carousel-lrg swiper-container\" data-swiper=\"{&quot;alignCells&quot;:false,&quot;autoPlay&quot;:true,&quot;autoPlaySpeed&quot;:3000,&quot;draggable&quot;:false,&quot;freeMode&quot;:false,&quot;loop&quot;:true,&quot;navigation&quot;:true,&quot;pageDots&quot;:false,&quot;pauseHover&quot;:false,&quot;responsiveHeight&quot;:false,&quot;slidesPerView&quot;:2,&quot;thumbnails&quot;:false,&quot;uuid&quot;:&quot;12345&quot;}\" style=\"height:400px\"><div class=\"swiper-wrapper\"><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\" tabindex=\"0\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" alt=\"\" class=\"wp-image-2164\" data-id=\"2164\" data-link=\"https:\/\/wwwcp.umes.edu\/commencement\/archives\/spring-2025-commencement\/2025-commencement-gallery\/dsc_1415\/\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1415-1024x681.jpeg\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1415-1024x681.jpeg 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1415-300x200.jpeg 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1415-768x511.jpeg 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1415-1536x1022.jpeg 1536w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1415-2048x1363.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\" tabindex=\"1\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" alt=\"\" class=\"wp-image-2163\" data-id=\"2163\" data-link=\"https:\/\/wwwcp.umes.edu\/commencement\/archives\/spring-2025-commencement\/2025-commencement-gallery\/dsc_2070\/\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2070-1024x681.jpeg\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2070-1024x681.jpeg 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2070-300x200.jpeg 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2070-768x511.jpeg 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2070-1536x1022.jpeg 1536w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2070-2048x1363.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\" tabindex=\"2\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" alt=\"\" class=\"wp-image-2162\" data-id=\"2162\" data-link=\"https:\/\/wwwcp.umes.edu\/commencement\/archives\/spring-2025-commencement\/2025-commencement-gallery\/dsc_2074-2\/\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2074-1-1024x681.jpeg\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2074-1-1024x681.jpeg 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2074-1-300x200.jpeg 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2074-1-768x511.jpeg 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2074-1-1536x1022.jpeg 1536w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2074-1-2048x1363.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\" tabindex=\"3\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" alt=\"\" class=\"wp-image-2161\" data-id=\"2161\" data-link=\"https:\/\/wwwcp.umes.edu\/commencement\/archives\/spring-2025-commencement\/2025-commencement-gallery\/dsc_2101\/\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2101-1024x681.jpeg\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2101-1024x681.jpeg 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2101-300x200.jpeg 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2101-768x511.jpeg 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2101-1536x1022.jpeg 1536w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2101-2048x1363.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\" tabindex=\"4\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" alt=\"\" class=\"wp-image-2160\" data-id=\"2160\" data-link=\"https:\/\/wwwcp.umes.edu\/commencement\/archives\/spring-2025-commencement\/2025-commencement-gallery\/dsc_1714\/\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1714-1024x681.jpeg\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1714-1024x681.jpeg 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1714-300x200.jpeg 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1714-768x511.jpeg 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1714-1536x1022.jpeg 1536w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1714-2048x1363.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\" tabindex=\"5\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" alt=\"\" class=\"wp-image-2159\" data-id=\"2159\" data-link=\"https:\/\/wwwcp.umes.edu\/commencement\/archives\/spring-2025-commencement\/2025-commencement-gallery\/dsc_2085-2\/\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2085-1-1024x681.jpeg\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2085-1-1024x681.jpeg 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2085-1-300x200.jpeg 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2085-1-768x511.jpeg 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2085-1-1536x1022.jpeg 1536w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2085-1-2048x1363.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\" tabindex=\"6\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" alt=\"\" class=\"wp-image-2158\" data-id=\"2158\" data-link=\"https:\/\/wwwcp.umes.edu\/commencement\/archives\/spring-2025-commencement\/2025-commencement-gallery\/dsc_2014\/\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2014-1024x681.jpeg\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2014-1024x681.jpeg 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2014-300x200.jpeg 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2014-768x511.jpeg 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2014-1536x1022.jpeg 1536w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2014-2048x1363.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\" tabindex=\"7\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" alt=\"\" class=\"wp-image-2157\" data-id=\"2157\" data-link=\"https:\/\/wwwcp.umes.edu\/commencement\/archives\/spring-2025-commencement\/2025-commencement-gallery\/dsc_1387\/\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1387-1024x681.jpeg\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1387-1024x681.jpeg 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1387-300x200.jpeg 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1387-768x511.jpeg 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1387-1536x1022.jpeg 1536w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1387-2048x1363.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\" tabindex=\"8\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-image-2156\" data-id=\"2156\" data-link=\"https:\/\/wwwcp.umes.edu\/commencement\/archives\/spring-2025-commencement\/2025-commencement-gallery\/image-88-2\/\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/Image-88-1-1024x683.jpeg\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/Image-88-1-1024x683.jpeg 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/Image-88-1-300x200.jpeg 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/Image-88-1-768x512.jpeg 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/Image-88-1-1536x1024.jpeg 1536w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\" tabindex=\"9\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"819\" alt=\"\" class=\"wp-image-2155\" data-id=\"2155\" data-link=\"https:\/\/wwwcp.umes.edu\/commencement\/archives\/spring-2025-commencement\/2025-commencement-gallery\/image-84\/\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/Image-84-1024x819.jpeg\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/Image-84-1024x819.jpeg 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/Image-84-300x240.jpeg 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/Image-84-768x614.jpeg 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/Image-84-1536x1229.jpeg 1536w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/Image-84-2048x1638.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\" tabindex=\"10\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"626\" alt=\"\" class=\"wp-image-2154\" data-id=\"2154\" data-link=\"https:\/\/wwwcp.umes.edu\/commencement\/archives\/spring-2025-commencement\/2025-commencement-gallery\/tgd-umesgraduation-051625-9572\/\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TGD-UMESGraduation-051625-9572-1024x626.jpeg\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TGD-UMESGraduation-051625-9572-1024x626.jpeg 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TGD-UMESGraduation-051625-9572-300x183.jpeg 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TGD-UMESGraduation-051625-9572-768x470.jpeg 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TGD-UMESGraduation-051625-9572-1536x939.jpeg 1536w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TGD-UMESGraduation-051625-9572-2048x1252.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\">Almost 300 graduates walked the stage Friday, May 16, 2025 during the University of Maryland Eastern Shore Spring Graduations that featured Maryland Gov. Wes Moore as commencements speaker. (Photo by Todd Dudek, UMES Ag Communications)<\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\" tabindex=\"11\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"874\" alt=\"\" class=\"wp-image-2153\" data-id=\"2153\" data-link=\"https:\/\/wwwcp.umes.edu\/commencement\/archives\/spring-2025-commencement\/2025-commencement-gallery\/td2-umesgraduation-051625-8111\/\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-8111-1024x874.jpeg\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-8111-1024x874.jpeg 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-8111-300x256.jpeg 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-8111-768x656.jpeg 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-8111-1536x1312.jpeg 1536w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-8111-2048x1749.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\">Almost 300 graduates walked the stage Friday, May 16, 2025 during the University of Maryland Eastern Shore Spring Graduations that featured Maryland Gov. Wes Moore as commencements speaker. (Photo by Todd Dudek, UMES Ag Communications)<\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\" tabindex=\"12\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"840\" alt=\"\" class=\"wp-image-2152\" data-id=\"2152\" data-link=\"https:\/\/wwwcp.umes.edu\/commencement\/archives\/spring-2025-commencement\/2025-commencement-gallery\/td2-umesgraduation-051625-8090-2\/\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-8090-1-1024x840.jpeg\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-8090-1-1024x840.jpeg 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-8090-1-300x246.jpeg 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-8090-1-768x630.jpeg 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-8090-1-1536x1260.jpeg 1536w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-8090-1-2048x1679.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\">Almost 300 graduates walked the stage Friday, May 16, 2025 during the University of Maryland Eastern Shore Spring Graduations that featured Maryland Gov. Wes Moore as commencements speaker. (Photo by Todd Dudek, UMES Ag Communications)<\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\" tabindex=\"13\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"655\" alt=\"\" class=\"wp-image-2150\" data-id=\"2150\" data-link=\"https:\/\/wwwcp.umes.edu\/commencement\/archives\/spring-2025-commencement\/2025-commencement-gallery\/td2-umesgraduation-051625-7960-2\/\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7960-1-1024x655.jpeg\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7960-1-1024x655.jpeg 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7960-1-300x192.jpeg 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7960-1-768x492.jpeg 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7960-1-1536x983.jpeg 1536w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7960-1-2048x1311.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\">Almost 300 graduates walked the stage Friday, May 16, 2025 during the University of Maryland Eastern Shore Spring Graduations that featured Maryland Gov. Wes Moore as commencements speaker. (Photo by Todd Dudek, UMES Ag Communications)<\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\" tabindex=\"14\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"518\" alt=\"\" class=\"wp-image-2149\" data-id=\"2149\" data-link=\"https:\/\/wwwcp.umes.edu\/commencement\/archives\/spring-2025-commencement\/2025-commencement-gallery\/td2-umesgraduation-051625-7928\/\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7928-1024x518.jpeg\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7928-1024x518.jpeg 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7928-300x152.jpeg 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7928-768x389.jpeg 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7928-1536x777.jpeg 1536w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7928-2048x1036.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\">Almost 300 graduates walked the stage Friday, May 16, 2025 during the University of Maryland Eastern Shore Spring Graduations that featured Maryland Gov. Wes Moore as commencements speaker. (Photo by Todd Dudek, UMES Ag Communications)<\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\" tabindex=\"15\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"833\" alt=\"\" class=\"wp-image-2151\" data-id=\"2151\" data-link=\"https:\/\/wwwcp.umes.edu\/commencement\/archives\/spring-2025-commencement\/2025-commencement-gallery\/td2-umesgraduation-051625-7898\/\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7898-1024x833.jpeg\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7898-1024x833.jpeg 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7898-300x244.jpeg 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7898-768x625.jpeg 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7898-1536x1249.jpeg 1536w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7898-2048x1666.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\">Almost 300 graduates walked the stage Friday, May 16, 2025 during the University of Maryland Eastern Shore Spring Graduations that featured Maryland Gov. Wes Moore as commencements speaker. (Photo by Todd Dudek, UMES Ag Communications)<\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\" tabindex=\"16\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" alt=\"\" class=\"wp-image-2116\" data-id=\"2116\" data-link=\"https:\/\/wwwcp.umes.edu\/commencement\/archives\/spring-2025-commencement\/image-4\/\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/image-4-1024x681.png\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/image-4-1024x681.png 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/image-4-300x199.png 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/image-4-768x510.png 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/image-4.png 1297w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\" tabindex=\"17\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" alt=\"\" class=\"wp-image-2115\" data-id=\"2115\" data-link=\"https:\/\/wwwcp.umes.edu\/commencement\/archives\/spring-2025-commencement\/image-3\/\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/image-3-1024x682.png\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/image-3-1024x682.png 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/image-3-300x200.png 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/image-3-768x511.png 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/image-3.png 1296w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\" tabindex=\"18\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"819\" alt=\"\" class=\"wp-image-2114\" data-id=\"2114\" data-link=\"https:\/\/wwwcp.umes.edu\/commencement\/archives\/spring-2025-commencement\/image-2\/\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/image-2-1024x819.jpg\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/image-2-1024x819.jpg 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/image-2-300x240.jpg 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/image-2-768x614.jpg 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/image-2-1536x1229.jpg 1536w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/image-2-2048x1638.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\" tabindex=\"19\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"837\" alt=\"\" class=\"wp-image-2107\" data-id=\"2107\" data-link=\"https:\/\/wwwcp.umes.edu\/commencement\/archives\/spring-2025-commencement\/image-1\/\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/image-1-1024x837.png\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/image-1-1024x837.png 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/image-1-300x245.png 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/image-1-768x628.png 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/image-1-1536x1256.png 1536w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/image-1.png 1676w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><div class=\"swiper-slide\"><div class=\"coblocks-gallery--item\" role=\"button\" tabindex=\"20\"><figure class=\"coblocks-gallery--figure has-margin-left-5 has-margin-left-mobile-5 has-margin-right-5 has-margin-right-mobile-5\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" alt=\"\" class=\"wp-image-2093\" data-id=\"2093\" data-link=\"https:\/\/wwwcp.umes.edu\/commencement\/archives\/spring-2025-commencement\/image\/\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/image-1024x682.png\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/image-1024x682.png 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/image-300x200.png 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/image-768x511.png 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/image-1536x1022.png 1536w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/image.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><figcaption class=\"coblocks-gallery--caption coblocks-gallery--primary-caption\"><\/figcaption><\/div><\/div><\/div><button class=\"nav-button__prev\" id=\"12345-prev\"><svg class=\"icon\" style=\"transform:rotate(180deg)\"><\/svg><\/button><button class=\"nav-button__next\" id=\"12345-next\"><svg class=\"icon\"><\/svg><\/button><\/div><\/div><\/div>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-3 is-cropped has-black-background-color has-background has-lightbox wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2048\" data-id=\"2155\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/Image-84-scaled.jpeg\" alt=\"\" class=\"wp-image-2155\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/Image-84-scaled.jpeg 2560w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/Image-84-300x240.jpeg 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/Image-84-1024x819.jpeg 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/Image-84-768x614.jpeg 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/Image-84-1536x1229.jpeg 1536w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/Image-84-2048x1638.jpeg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1703\" data-id=\"2164\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1415-scaled.jpeg\" alt=\"\" class=\"wp-image-2164\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1415-scaled.jpeg 2560w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1415-300x200.jpeg 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1415-1024x681.jpeg 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1415-768x511.jpeg 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1415-1536x1022.jpeg 1536w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1415-2048x1363.jpeg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1638\" data-id=\"2150\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7960-1-scaled.jpeg\" alt=\"\" class=\"wp-image-2150\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7960-1-scaled.jpeg 2560w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7960-1-300x192.jpeg 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7960-1-1024x655.jpeg 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7960-1-768x492.jpeg 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7960-1-1536x983.jpeg 1536w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7960-1-2048x1311.jpeg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2186\" data-id=\"2153\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-8111-scaled.jpeg\" alt=\"\" class=\"wp-image-2153\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-8111-scaled.jpeg 2560w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-8111-300x256.jpeg 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-8111-1024x874.jpeg 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-8111-768x656.jpeg 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-8111-1536x1312.jpeg 1536w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-8111-2048x1749.jpeg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"8049\" height=\"5366\" data-id=\"2156\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/Image-88-1.jpeg\" alt=\"\" class=\"wp-image-2156\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/Image-88-1.jpeg 8049w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/Image-88-1-300x200.jpeg 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/Image-88-1-1024x683.jpeg 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/Image-88-1-768x512.jpeg 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/Image-88-1-1536x1024.jpeg 1536w\" sizes=\"auto, (max-width: 8049px) 100vw, 8049px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1565\" data-id=\"2154\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TGD-UMESGraduation-051625-9572-scaled.jpeg\" alt=\"\" class=\"wp-image-2154\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TGD-UMESGraduation-051625-9572-scaled.jpeg 2560w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TGD-UMESGraduation-051625-9572-300x183.jpeg 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TGD-UMESGraduation-051625-9572-1024x626.jpeg 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TGD-UMESGraduation-051625-9572-768x470.jpeg 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TGD-UMESGraduation-051625-9572-1536x939.jpeg 1536w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TGD-UMESGraduation-051625-9572-2048x1252.jpeg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1703\" data-id=\"2161\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2101-scaled.jpeg\" alt=\"\" class=\"wp-image-2161\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2101-scaled.jpeg 2560w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2101-300x200.jpeg 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2101-1024x681.jpeg 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2101-768x511.jpeg 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2101-1536x1022.jpeg 1536w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2101-2048x1363.jpeg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1703\" data-id=\"2163\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2070-scaled.jpeg\" alt=\"\" class=\"wp-image-2163\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2070-scaled.jpeg 2560w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2070-300x200.jpeg 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2070-1024x681.jpeg 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2070-768x511.jpeg 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2070-1536x1022.jpeg 1536w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2070-2048x1363.jpeg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2099\" data-id=\"2152\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-8090-1-scaled.jpeg\" alt=\"\" class=\"wp-image-2152\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-8090-1-scaled.jpeg 2560w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-8090-1-300x246.jpeg 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-8090-1-1024x840.jpeg 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-8090-1-768x630.jpeg 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-8090-1-1536x1260.jpeg 1536w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-8090-1-2048x1679.jpeg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1703\" data-id=\"2157\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1387-scaled.jpeg\" alt=\"\" class=\"wp-image-2157\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1387-scaled.jpeg 2560w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1387-300x200.jpeg 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1387-1024x681.jpeg 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1387-768x511.jpeg 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1387-1536x1022.jpeg 1536w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1387-2048x1363.jpeg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1295\" data-id=\"2149\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7928-scaled.jpeg\" alt=\"\" class=\"wp-image-2149\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7928-scaled.jpeg 2560w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7928-300x152.jpeg 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7928-1024x518.jpeg 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7928-768x389.jpeg 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7928-1536x777.jpeg 1536w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7928-2048x1036.jpeg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1703\" data-id=\"2158\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2014-scaled.jpeg\" alt=\"\" class=\"wp-image-2158\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2014-scaled.jpeg 2560w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2014-300x200.jpeg 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2014-1024x681.jpeg 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2014-768x511.jpeg 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2014-1536x1022.jpeg 1536w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2014-2048x1363.jpeg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1703\" data-id=\"2159\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2085-1-scaled.jpeg\" alt=\"\" class=\"wp-image-2159\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2085-1-scaled.jpeg 2560w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2085-1-300x200.jpeg 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2085-1-1024x681.jpeg 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2085-1-768x511.jpeg 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2085-1-1536x1022.jpeg 1536w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2085-1-2048x1363.jpeg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1703\" data-id=\"2160\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1714-scaled.jpeg\" alt=\"\" class=\"wp-image-2160\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1714-scaled.jpeg 2560w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1714-300x200.jpeg 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1714-1024x681.jpeg 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1714-768x511.jpeg 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1714-1536x1022.jpeg 1536w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_1714-2048x1363.jpeg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1703\" data-id=\"2162\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2074-1-scaled.jpeg\" alt=\"\" class=\"wp-image-2162\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2074-1-scaled.jpeg 2560w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2074-1-300x200.jpeg 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2074-1-1024x681.jpeg 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2074-1-768x511.jpeg 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2074-1-1536x1022.jpeg 1536w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/DSC_2074-1-2048x1363.jpeg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2082\" data-id=\"2151\" src=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7898-scaled.jpeg\" alt=\"\" class=\"wp-image-2151\" srcset=\"https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7898-scaled.jpeg 2560w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7898-300x244.jpeg 300w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7898-1024x833.jpeg 1024w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7898-768x625.jpeg 768w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7898-1536x1249.jpeg 1536w, https:\/\/wwwcp.umes.edu\/commencement\/wp-content\/uploads\/sites\/84\/2025\/06\/TD2-UMESGraduation-051625-7898-2048x1666.jpeg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>&#8230;<span class=\"cpschool-read-more-link-holder\"><a class=\"btn btn-basic cpschool-read-more-link\" href=\"https:\/\/wwwcp.umes.edu\/commencement\/archives\/spring-2025-commencement\/2025-commencement-gallery\/\">Read more <span class=\"sr-only\">Spring 2025 Commencement Gallery<\/span><\/a><\/span><\/p>\n","protected":false},"author":2163,"featured_media":0,"parent":2083,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"folder":[],"class_list":["post-2148","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/wwwcp.umes.edu\/commencement\/wp-json\/wp\/v2\/pages\/2148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wwwcp.umes.edu\/commencement\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wwwcp.umes.edu\/commencement\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wwwcp.umes.edu\/commencement\/wp-json\/wp\/v2\/users\/2163"}],"replies":[{"embeddable":true,"href":"https:\/\/wwwcp.umes.edu\/commencement\/wp-json\/wp\/v2\/comments?post=2148"}],"version-history":[{"count":0,"href":"https:\/\/wwwcp.umes.edu\/commencement\/wp-json\/wp\/v2\/pages\/2148\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/wwwcp.umes.edu\/commencement\/wp-json\/wp\/v2\/pages\/2083"}],"wp:attachment":[{"href":"https:\/\/wwwcp.umes.edu\/commencement\/wp-json\/wp\/v2\/media?parent=2148"}],"wp:term":[{"taxonomy":"folder","embeddable":true,"href":"https:\/\/wwwcp.umes.edu\/commencement\/wp-json\/wp\/v2\/folder?post=2148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}