{"id":1771,"date":"2021-08-02T14:35:25","date_gmt":"2021-08-02T18:35:25","guid":{"rendered":"https:\/\/wwwcp.umes.edu\/academic\/?page_id=1771"},"modified":"2025-10-14T09:33:34","modified_gmt":"2025-10-14T13:33:34","slug":"deans","status":"publish","type":"page","link":"https:\/\/wwwcp.umes.edu\/academic\/deans\/","title":{"rendered":"Deans"},"content":{"rendered":"\n<div class=\"wp-block-group staff-member\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"545\" height=\"545\" src=\"https:\/\/wwwcp.umes.edu\/academic\/wp-content\/uploads\/sites\/53\/2021\/12\/TSV.jpeg\" alt=\"\" class=\"wp-image-2459\" srcset=\"https:\/\/wwwcp.umes.edu\/academic\/wp-content\/uploads\/sites\/53\/2021\/12\/TSV.jpeg 545w, https:\/\/wwwcp.umes.edu\/academic\/wp-content\/uploads\/sites\/53\/2021\/12\/TSV-300x300.jpeg 300w, https:\/\/wwwcp.umes.edu\/academic\/wp-content\/uploads\/sites\/53\/2021\/12\/TSV-150x150.jpeg 150w, https:\/\/wwwcp.umes.edu\/academic\/wp-content\/uploads\/sites\/53\/2021\/12\/TSV-200x200.jpeg 200w, https:\/\/wwwcp.umes.edu\/academic\/wp-content\/uploads\/sites\/53\/2021\/12\/TSV-50x50.jpeg 50w\" sizes=\"auto, (max-width: 545px) 100vw, 545px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p class=\"has-asap-font-family has-custom-font wp-block-paragraph\" style=\"font-family:Asap\"><strong>Dr. T. Sean Vasaitis<\/strong><br>Dean<br>School of Pharmacy and Health Professions<br>Phone: (410) 651-8350<br>Email:&nbsp;<a href=\"mailto:tsvasaitis@umes.edu\">tsvasaitis@umes.edu<\/a> <br>Website:&nbsp;<a href=\"https:\/\/www.umes.edu\/SHP\/\">https:\/\/www.umes.edu\/SHP\/<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"727\" height=\"1024\" src=\"https:\/\/wwwcp.umes.edu\/academic\/wp-content\/uploads\/sites\/53\/2021\/09\/DrDerrekDunn-727x1024.jpg\" alt=\"\" class=\"wp-image-2368\" srcset=\"https:\/\/wwwcp.umes.edu\/academic\/wp-content\/uploads\/sites\/53\/2021\/09\/DrDerrekDunn-727x1024.jpg 727w, https:\/\/wwwcp.umes.edu\/academic\/wp-content\/uploads\/sites\/53\/2021\/09\/DrDerrekDunn-213x300.jpg 213w, https:\/\/wwwcp.umes.edu\/academic\/wp-content\/uploads\/sites\/53\/2021\/09\/DrDerrekDunn-768x1081.jpg 768w, https:\/\/wwwcp.umes.edu\/academic\/wp-content\/uploads\/sites\/53\/2021\/09\/DrDerrekDunn-1091x1536.jpg 1091w, https:\/\/wwwcp.umes.edu\/academic\/wp-content\/uploads\/sites\/53\/2021\/09\/DrDerrekDunn-1455x2048.jpg 1455w, https:\/\/wwwcp.umes.edu\/academic\/wp-content\/uploads\/sites\/53\/2021\/09\/DrDerrekDunn-scaled.jpg 1818w\" sizes=\"auto, (max-width: 727px) 100vw, 727px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p class=\"has-asap-font-family has-custom-font wp-block-paragraph\" style=\"font-family:Asap\"><strong>Dr. Derrek B. Dunn<\/strong><br>Dean&nbsp;<br>School of Business, Engineering, Applied Sciences, Technology, and Tourism Management<br>Phone: (410) 651-6067<br>Email:&nbsp;<a href=\"mailto:ddunn@umes.edu\">ddunn@umes.edu<\/a><br>Website:&nbsp;<a href=\"https:\/\/www.umes.edu\/SBT\/\">https:\/\/www.umes.edu\/SBT\/<\/a>&nbsp;<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"196\" height=\"244\" src=\"https:\/\/wwwcp.umes.edu\/academic\/wp-content\/uploads\/sites\/53\/2021\/08\/Lakeisha-Harris.jpg\" alt=\"\" class=\"wp-image-1774\"\/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p class=\"has-asap-font-family has-custom-font wp-block-paragraph\" style=\"font-family:Asap\"><strong>Dr. LaKeisha L. Harris<\/strong><br>Dean of Graduate Studies<br>School of Graduate Studies<br>Phone: (410) 651-7966<br>Email:&nbsp;<a href=\"mailto:llharris@umes.edu\">llharris@umes.edu<\/a><br>Website:&nbsp;<a href=\"https:\/\/www.umes.edu\/Grad\/\">https:\/\/www.umes.edu\/Grad\/<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"305\" src=\"https:\/\/wwwcp.umes.edu\/academic\/wp-content\/uploads\/sites\/53\/2021\/09\/Kairo-prefered-desk.1.png\" alt=\"\" class=\"wp-image-2371\" srcset=\"https:\/\/wwwcp.umes.edu\/academic\/wp-content\/uploads\/sites\/53\/2021\/09\/Kairo-prefered-desk.1.png 300w, https:\/\/wwwcp.umes.edu\/academic\/wp-content\/uploads\/sites\/53\/2021\/09\/Kairo-prefered-desk.1-295x300.png 295w, https:\/\/wwwcp.umes.edu\/academic\/wp-content\/uploads\/sites\/53\/2021\/09\/Kairo-prefered-desk.1-50x50.png 50w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p class=\"has-asap-font-family has-custom-font wp-block-paragraph\" style=\"font-family:Asap\"><strong>Dr. Moses T. Kairo<\/strong><br>Dean<br>School of Agricultural and Natural Sciences<br>Phone: (410) 651-6072<br>Email:&nbsp;<a href=\"mailto:mkairo@umes.edu\">mkairo@umes.edu<\/a><br>Website:&nbsp;<a href=\"https:\/\/www.umes.edu\/sans\/\">https:\/\/www.umes.edu\/sans\/<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/wwwcp.umes.edu\/academic\/wp-content\/uploads\/sites\/53\/2024\/02\/Mr.-Harrington.jpg\" alt=\"\"\/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p class=\"has-asap-font-family has-custom-font wp-block-paragraph\" style=\"font-family:Asap\"><strong>Mr. Christopher J. Harrington<\/strong><br>Dean<br>School of Education, Social Sciences, and the Arts<br>Phone: (410) 651-6488<br>Email: <a href=\"mailto:cjharrington@umes.edu\" target=\"_blank\" rel=\"noreferrer noopener\">cjharrington@umes.edu<\/a><br>Website: <a href=\"https:\/\/www.umes.edu\/SESA\/\">https:\/\/www.umes.edu\/SESA\/<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"669\" src=\"https:\/\/wwwcp.umes.edu\/academic\/wp-content\/uploads\/sites\/53\/2025\/01\/Stanley-Robertson-2-scaled-e1720789836640-768x669-4.jpeg\" alt=\"\" class=\"wp-image-2987\" srcset=\"https:\/\/wwwcp.umes.edu\/academic\/wp-content\/uploads\/sites\/53\/2025\/01\/Stanley-Robertson-2-scaled-e1720789836640-768x669-4.jpeg 768w, https:\/\/wwwcp.umes.edu\/academic\/wp-content\/uploads\/sites\/53\/2025\/01\/Stanley-Robertson-2-scaled-e1720789836640-768x669-4-300x261.jpeg 300w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p class=\"has-asap-font-family has-custom-font wp-block-paragraph\" style=\"font-family:Asap\"><strong>Dr. Stanley Robertson<\/strong><br>Dean<br>School of Veterinary Medicine<br>Phone: (410) 651-7163<br>Email: <a href=\"srrobertson@umes.edu\" data-type=\"URL\" data-id=\"srrobertson@umes.edu\" target=\"_blank\" rel=\"noreferrer noopener\">srrobertson@umes.edu<\/a><br>Website: <a href=\"https:\/\/wwwcp.umes.edu\/pr\/umes-hires-first-permanent-dean-for-school-of-veterinary-medicine\/\" data-type=\"URL\" data-id=\"https:\/\/wwwcp.umes.edu\/pr\/umes-hires-first-permanent-dean-for-school-of-veterinary-medicine\/\">https:\/\/www.umes.edu<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-asap-font-family has-custom-font wp-block-paragraph\" style=\"font-family:Asap\"><strong><span style=\"text-decoration: underline\" class=\"underline\">Contact Information<br><\/span><\/strong>Office of the Provost and Vice President for Academic Affairs<br>University of Maryland Eastern Shore<br>11868 Academic Oval, John T. Williams Hall Suite 3111<br>Princess Anne, Maryland 21853<br>Telephone: (410) 651-6508 or 6713<\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dr. T. Sean VasaitisDeanSchool of Pharmacy and Health ProfessionsPhone: (410) 651-8350Email:&nbsp;tsvasaitis@umes.edu Website:&nbsp;https:\/\/www.umes.edu\/SHP\/ Dr. Derrek B. DunnDean&nbsp;School of Business, Engineering, Applied Sciences, Technology, and Tourism ManagementPhone: (410) 651-6067Email:&nbsp;ddunn@umes.eduWebsite:&nbsp;https:\/\/www.umes.edu\/SBT\/&nbsp; Dr. LaKeisha L. HarrisDean of Graduate StudiesSchool of Graduate StudiesPhone: (410) 651-7966Email:&nbsp;llharris@umes.eduWebsite:&nbsp;https:\/\/www.umes.edu\/Grad\/ Dr. Moses T. KairoDeanSchool of Agricultural and Natural SciencesPhone: (410) 651-6072Email:&nbsp;mkairo@umes.eduWebsite:&nbsp;https:\/\/www.umes.edu\/sans\/ Mr. Christopher J. HarringtonDeanSchool of&#8230;<span class=\"cpschool-read-more-link-holder\"><a class=\"btn btn-basic cpschool-read-more-link\" href=\"https:\/\/wwwcp.umes.edu\/academic\/deans\/\">Read more <span class=\"sr-only\">Deans<\/span><\/a><\/span><\/p>\n","protected":false},"author":21,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_coblocks_attr":"Asap,Asap","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"folder":[],"class_list":["post-1771","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/wwwcp.umes.edu\/academic\/wp-json\/wp\/v2\/pages\/1771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wwwcp.umes.edu\/academic\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wwwcp.umes.edu\/academic\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wwwcp.umes.edu\/academic\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/wwwcp.umes.edu\/academic\/wp-json\/wp\/v2\/comments?post=1771"}],"version-history":[{"count":0,"href":"https:\/\/wwwcp.umes.edu\/academic\/wp-json\/wp\/v2\/pages\/1771\/revisions"}],"wp:attachment":[{"href":"https:\/\/wwwcp.umes.edu\/academic\/wp-json\/wp\/v2\/media?parent=1771"}],"wp:term":[{"taxonomy":"folder","embeddable":true,"href":"https:\/\/wwwcp.umes.edu\/academic\/wp-json\/wp\/v2\/folder?post=1771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}